{"id":106,"date":"2022-09-29T09:49:00","date_gmt":"2022-09-29T09:49:00","guid":{"rendered":"https:\/\/aircompressorforlasercutter.com\/china-good-quality-air-end-laser-cutting-air-compressor-with-dryer-and-tank-scr10cpm-with-good-quality\/"},"modified":"2022-09-29T09:49:00","modified_gmt":"2022-09-29T09:49:00","slug":"china-good-quality-air-end-laser-cutting-air-compressor-with-dryer-and-tank-scr10cpm-with-good-quality","status":"publish","type":"post","link":"https:\/\/aircompressorforlasercutter.com\/fr\/application\/compresseur-dair-de-decoupe-laser-scr10cpm-de-bonne-qualite-avec-secheur-et-reservoir\/","title":{"rendered":"Compresseur d'air de d\u00e9coupe laser de haute qualit\u00e9, avec s\u00e9cheur et r\u00e9servoir (SCR10CPM), fabriqu\u00e9 en Chine."},"content":{"rendered":"<p><h2>Description de l'article<\/h2>\n<p>\n<p>   <strong>Description de l'article<\/strong><\/p>\n<p><\/p>\n<p><p><strong>Caract\u00e9ristiques du produit<\/strong><br \/>1. Relation conique, sans roulement et entretien moteur gratuit.<br \/>2. Moteur PM avec protection IP65.<br \/>3. Protection PTC int\u00e9gr\u00e9e pour moteur PM.<br \/>4. Moteur PM de haute qualit\u00e9.<br \/>5. Fournisseur de moteurs PM plus fiable.<br \/>6. Bloc compresseur haute performance.<br \/>sept. Nouvel onduleur V\/F.<br \/>huit. Entretien facile.<br \/>9. Tout en 1.<\/p>\n<p><strong>Types de solutions<\/p>\n<p>Avantages<\/p>\n<p><\/strong><\/p>\n<p><strong>Logiciel<br \/><\/strong><\/p>\n<p><strong>\u00c0 propos de SCR<\/p>\n<p><\/strong><br \/>De plus, depuis 2008, nous exportons nos produits vers plus de 55 pays, dont le Royaume-Uni, les \u00c9tats-Unis, l'Espagne et bien d'autres. Nous avons \u00e9galement \u00e9tabli des relations durables avec nos partenaires, qui font confiance \u00e0 la qualit\u00e9 sup\u00e9rieure de nos produits.<br \/>En dehors de cette production annuelle, nous pouvons fabriquer pr\u00e8s de 7 000 compresseurs par an, dont environ 301 TP3T sont destin\u00e9s au march\u00e9 \u00e9tranger.\u00a0<\/p>\n<p><strong>FAQ<\/strong><\/p>\n<p><p>Contactez-nous<\/p>\n<p>Titre de l'organisation : ZheJiang Screw Compressor Co., Ltd<br \/>Prenez contact avec la personne suivante\u00a0: Vincent Solar<br \/>\u00a0<\/p>\n<p>Si l'un de nos produits vous int\u00e9resse, n'h\u00e9sitez surtout pas \u00e0 nous contacter. Nous esp\u00e9rons sinc\u00e8rement collaborer, nous d\u00e9velopper et \u00e9tablir une relation durable avec vous.<\/p>\n<p>\u00a0  <\/p>\n<p>\n<p>\n<p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<td colspan=\"2\" rowspan=\"2\">Mod\u00e8le<\/td>\n<td rowspan=\"2\" style=\"width:136px\">SCR10CPM-7<\/td>\n<td rowspan=\"2\" style=\"width:131px\">SCR10CPM-8<\/td>\n<td rowspan=\"2\" style=\"width:148px\">SCR10CPM-10<\/td>\n<\/tr>\n<tr><\/tr>\n<tr>\n<td colspan=\"2\">Capacit\u00e9\/Pression (m3\/min,\/BAR)<\/td>\n<td style=\"width:136px\">1.15\/7<\/td>\n<td style=\"width:131px\">1.1\/8<\/td>\n<td style=\"width:148px\">0.95\/10<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"6\">Moteur<\/td>\n<td>Puissance (kW)<\/td>\n<td colspan=\"3\" style=\"width:428px\">7,5 kW (10 ch)<\/td>\n<\/tr>\n<tr>\n<td>Vitesse (tr\/min)<\/td>\n<td style=\"width:136px\">1200\/3000&nbsp;<\/td>\n<td style=\"width:131px\">1200\/3000<\/td>\n<td style=\"width:148px\">1400\/2600<\/td>\n<\/tr>\n<tr>\n<td>Type de moteur<\/td>\n<td colspan=\"3\" style=\"width:428px\">Moteur PM \u00e0 refroidissement par huile<\/td>\n<\/tr>\n<tr>\n<td>Volt (V)<\/td>\n<td colspan=\"3\" style=\"width:428px\">380\/400\/415(220)<\/td>\n<\/tr>\n<tr>\n<td>niveau de s\u00e9curit\u00e9 automobile<\/td>\n<td colspan=\"3\" style=\"width:428px\">IP65<\/td>\n<\/tr>\n<tr>\n<td>Niveau d'isolation du moteur<\/td>\n<td colspan=\"3\" style=\"width:428px\">F<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Alimentation \u00e9lectrique<\/td>\n<td colspan=\"3\" style=\"width:428px\">380 (400, 415) V\/50 Hz\/triphas\u00e9, 220 V\/60 Hz\/triphas\u00e9<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Temp\u00e9rature de sortie (\u00baC)<\/td>\n<td colspan=\"3\" style=\"width:428px\">\u2264 Temp\u00e9rature ambiante +10\u00baC<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Chemin de fer<\/td>\n<td colspan=\"3\" style=\"width:428px\">Entra\u00eenement direct<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Niveau sonore \u00e0 1 m\u00e8tre<\/td>\n<td colspan=\"3\" style=\"width:428px\">67\u00b13dB(A)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">m\u00e9thode de refroidissement<\/td>\n<td colspan=\"3\" style=\"width:428px\">Refroidi par air<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">teneur en huile<\/td>\n<td colspan=\"3\" style=\"width:428px\">\u22640,1<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Prise de courant<\/td>\n<td colspan=\"3\" style=\"width:428px\">Rc 1\/2<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"3\">Dimension<\/td>\n<td>Longueur (mm)<\/td>\n<td colspan=\"3\" style=\"width:428px\">1720<\/td>\n<\/tr>\n<tr>\n<td>Largeur (mm)<\/td>\n<td colspan=\"3\" style=\"width:428px\">605<\/td>\n<\/tr>\n<tr>\n<td>Hauteur (mm)<\/td>\n<td colspan=\"3\" style=\"width:428px\">1260<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Poids (kg)<\/td>\n<td colspan=\"3\" style=\"width:428px\">290<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<td>\n<p><strong>1. Quelles sont nos conditions commerciales ? Quel type de devise de r\u00e8glement proposons-nous ?<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Conditions commerciales : CIF, CFR, FOB, Ex-Works&nbsp;<br \/>Quant \u00e0 notre entreprise, elle effectuait ses transactions en dollars, en euros et en RMB.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><strong>2&nbsp;<\/strong><strong>&nbsp;&nbsp;Quel est le d\u00e9lai de livraison ?<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Notre d\u00e9lai de livraison standard est de 30 \u00e0 40 jours apr\u00e8s confirmation de la commande et r\u00e9ception des re\u00e7us pour les compresseurs standard ; pour les autres exigences non standard, les d\u00e9lais seront discut\u00e9s au cas par cas.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><strong>3&nbsp;<\/strong><strong>&nbsp;&nbsp;Quelle est la tension du compresseur ?<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Les tensions disponibles sont les suivantes\u00a0: 380\u00a0V\/50\u00a0Hz\/triphas\u00e9, 400\u00a0V\/50\u00a0Hz\/triphas\u00e9, 415\u00a0V\/50\u00a0Hz\/triphas\u00e9, 220\u00a0V\/60\u00a0Hz\/triphas\u00e9, 380\u00a0V\/60\u00a0Hz\/triphas\u00e9 et 440\u00a0V\/60\u00a0Hz\/triphas\u00e9. Nous fournissons \u00e9galement d\u2019autres tensions sur demande.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><strong>4&nbsp;<\/strong><strong>&nbsp;Notre compresseur peut-il fonctionner dans un environnement \u00e0 haute temp\u00e9rature\u00a0? Quelle est la plage de temp\u00e9ratures de fonctionnement de notre machine\u00a0?<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Oui, notre machine fonctionnerait dans un environnement \u00e0 haute temp\u00e9rature ; jusqu'\u00e0 pr\u00e9sent, nos produits ont \u00e9t\u00e9 vendus dans de nombreux pays connaissant des temp\u00e9ratures \u00e9lev\u00e9es en \u00e9t\u00e9, comme l'Irak, l'Arabie saoudite, l'\u00c9gypte, l'Alg\u00e9rie, etc.&nbsp;<br \/>Plage de temp\u00e9rature de fonctionnement : 1-45 \u00baC (33,8\u00baF-113\u00baF)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><strong>5&nbsp;<\/strong><strong>&nbsp;Quel est le min.&nbsp;<\/strong><strong>O<\/strong><strong>exigence de commande ?<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>La quantit\u00e9 minimale de commande est de 1 pi\u00e8ce.&nbsp;<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<td colspan=\"2\" rowspan=\"2\">Mod\u00e8le<\/td>\n<td rowspan=\"2\" style=\"width:136px\">SCR10CPM-7<\/td>\n<td rowspan=\"2\" style=\"width:131px\">SCR10CPM-8<\/td>\n<td rowspan=\"2\" style=\"width:148px\">SCR10CPM-10<\/td>\n<\/tr>\n<tr><\/tr>\n<tr>\n<td colspan=\"2\">Capacit\u00e9\/Pression (m3\/min,\/BAR)<\/td>\n<td style=\"width:136px\">1.15\/7<\/td>\n<td style=\"width:131px\">1.1\/8<\/td>\n<td style=\"width:148px\">0.95\/10<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"6\">Moteur<\/td>\n<td>Puissance (kW)<\/td>\n<td colspan=\"3\" style=\"width:428px\">7,5 kW (10 ch)<\/td>\n<\/tr>\n<tr>\n<td>Vitesse (tr\/min)<\/td>\n<td style=\"width:136px\">1200\/3000&nbsp;<\/td>\n<td style=\"width:131px\">1200\/3000<\/td>\n<td style=\"width:148px\">1400\/2600<\/td>\n<\/tr>\n<tr>\n<td>Type de moteur<\/td>\n<td colspan=\"3\" style=\"width:428px\">Moteur PM \u00e0 refroidissement par huile<\/td>\n<\/tr>\n<tr>\n<td>Volt (V)<\/td>\n<td colspan=\"3\" style=\"width:428px\">380\/400\/415(220)<\/td>\n<\/tr>\n<tr>\n<td>niveau de s\u00e9curit\u00e9 automobile<\/td>\n<td colspan=\"3\" style=\"width:428px\">IP65<\/td>\n<\/tr>\n<tr>\n<td>Niveau d'isolation du moteur<\/td>\n<td colspan=\"3\" style=\"width:428px\">F<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Alimentation \u00e9lectrique<\/td>\n<td colspan=\"3\" style=\"width:428px\">380 (400, 415) V\/50 Hz\/triphas\u00e9, 220 V\/60 Hz\/triphas\u00e9<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Temp\u00e9rature de sortie (\u00baC)<\/td>\n<td colspan=\"3\" style=\"width:428px\">\u2264 Temp\u00e9rature ambiante +10\u00baC<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Chemin de fer<\/td>\n<td colspan=\"3\" style=\"width:428px\">Entra\u00eenement direct<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Niveau sonore \u00e0 1 m\u00e8tre<\/td>\n<td colspan=\"3\" style=\"width:428px\">67\u00b13dB(A)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">m\u00e9thode de refroidissement<\/td>\n<td colspan=\"3\" style=\"width:428px\">Refroidi par air<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">teneur en huile<\/td>\n<td colspan=\"3\" style=\"width:428px\">\u22640,1<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Prise de courant<\/td>\n<td colspan=\"3\" style=\"width:428px\">Rc 1\/2<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"3\">Dimension<\/td>\n<td>Longueur (mm)<\/td>\n<td colspan=\"3\" style=\"width:428px\">1720<\/td>\n<\/tr>\n<tr>\n<td>Largeur (mm)<\/td>\n<td colspan=\"3\" style=\"width:428px\">605<\/td>\n<\/tr>\n<tr>\n<td>Hauteur (mm)<\/td>\n<td colspan=\"3\" style=\"width:428px\">1260<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Poids (kg)<\/td>\n<td colspan=\"3\" style=\"width:428px\">290<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<td>\n<p><strong>1. Quelles sont nos conditions commerciales ? Quel type de devise de r\u00e8glement proposons-nous ?<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Conditions commerciales : CIF, CFR, FOB, Ex-Works&nbsp;<br \/>Quant \u00e0 notre entreprise, elle effectuait ses transactions en dollars, en euros et en RMB.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><strong>2&nbsp;<\/strong><strong>&nbsp;&nbsp;Quel est le d\u00e9lai de livraison ?<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Notre d\u00e9lai de livraison standard est de 30 \u00e0 40 jours apr\u00e8s confirmation de la commande et r\u00e9ception des re\u00e7us pour les compresseurs standard ; pour les autres exigences non standard, les d\u00e9lais seront discut\u00e9s au cas par cas.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><strong>3&nbsp;<\/strong><strong>&nbsp;&nbsp;Quelle est la tension du compresseur ?<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Les tensions disponibles sont les suivantes\u00a0: 380\u00a0V\/50\u00a0Hz\/triphas\u00e9, 400\u00a0V\/50\u00a0Hz\/triphas\u00e9, 415\u00a0V\/50\u00a0Hz\/triphas\u00e9, 220\u00a0V\/60\u00a0Hz\/triphas\u00e9, 380\u00a0V\/60\u00a0Hz\/triphas\u00e9 et 440\u00a0V\/60\u00a0Hz\/triphas\u00e9. Nous fournissons \u00e9galement d\u2019autres tensions sur demande.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><strong>4&nbsp;<\/strong><strong>&nbsp;Notre compresseur peut-il fonctionner dans un environnement \u00e0 haute temp\u00e9rature\u00a0? Quelle est la plage de temp\u00e9ratures de fonctionnement de notre machine\u00a0?<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Oui, notre machine fonctionnerait dans un environnement \u00e0 haute temp\u00e9rature ; jusqu'\u00e0 pr\u00e9sent, nos produits ont \u00e9t\u00e9 vendus dans de nombreux pays connaissant des temp\u00e9ratures \u00e9lev\u00e9es en \u00e9t\u00e9, comme l'Irak, l'Arabie saoudite, l'\u00c9gypte, l'Alg\u00e9rie, etc.&nbsp;<br \/>Plage de temp\u00e9rature de fonctionnement : 1-45 \u00baC (33,8\u00baF-113\u00baF)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><strong>5&nbsp;<\/strong><strong>&nbsp;Quel est le min.&nbsp;<\/strong><strong>O<\/strong><strong>exigence de commande ?<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>La quantit\u00e9 minimale de commande est de 1 pi\u00e8ce.&nbsp;<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><h2>Comment r\u00e9parer et entretenir un compresseur d'air<\/h2>\n<p>Un compresseur est un appareil servant \u00e0 d\u00e9placer l'air d'un endroit \u00e0 un autre. L'air p\u00e9n\u00e8tre dans le compresseur par la soupape d'admission. \u00c0 l'int\u00e9rieur du compresseur, les ailettes du rotor interne tournent dans une cavit\u00e9 excentr\u00e9e. Le bras \u00e0 longueur r\u00e9glable divise cet espace en plusieurs cavit\u00e9s de tailles diff\u00e9rentes. Lorsque le rotor tourne, l'air remplit la cavit\u00e9. En circulant dans la cavit\u00e9, l'air se comprime et est expuls\u00e9 par la sortie du compresseur.<\/p>\n<h2>D\u00e9placement positif<\/h2>\n<p>Les compresseurs d'air volum\u00e9triques utilisent un piston alternatif pour comprimer l'air. Lors de la phase d'aspiration, le gaz est aspir\u00e9 puis comprim\u00e9 par le mouvement inverse du piston. L'air comprim\u00e9 est ensuite refoul\u00e9 par le m\u00eame mouvement. Ce type de compresseur est couramment utilis\u00e9 dans les automobiles, les r\u00e9frig\u00e9rateurs et autres applications n\u00e9cessitant une pression \u00e9lev\u00e9e. Cependant, son rendement est inf\u00e9rieur \u00e0 celui d'un compresseur centrifuge.<br \/>La plupart des compresseurs d'air modernes sont \u00e0 d\u00e9placement positif. Ces compresseurs aspirent un volume d'air dans la chambre de compression et le redistribuent lorsque la pompe fonctionne \u00e0 pleine capacit\u00e9. Ils sont plus \u00e9conomiques que les compresseurs \u00e0 d\u00e9placement n\u00e9gatif. Les compresseurs d'air \u00e0 vis alternatifs sont les plus courants. Ce type de compresseur est dot\u00e9 d'une chemise d'eau autour du cylindre et est fr\u00e9quemment utilis\u00e9 dans des proc\u00e9d\u00e9s tels que le forage p\u00e9trolier.<br \/>Une pompe \u00e0 v\u00e9lo est un exemple de compression volum\u00e9trique. L'air est aspir\u00e9 dans le cylindre et comprim\u00e9 par le piston. Un compresseur \u00e0 piston fonctionne selon le m\u00eame principe, mais il utilise un vilebrequin ou une bielle pour actionner le piston. Il existe deux types de compresseurs volum\u00e9triques\u00a0: les compresseurs \u00e0 simple effet et les compresseurs \u00e0 double effet. Ces deux types fonctionnent selon le m\u00eame principe\u00a0; la diff\u00e9rence r\u00e9side dans le taux de compression.<br \/>En compression d'air, la compression volum\u00e9trique r\u00e9duit le volume et la viscosit\u00e9 du fluide. Il en r\u00e9sulte des taux de compression plus \u00e9lev\u00e9s. Ce proc\u00e9d\u00e9 est utilis\u00e9 dans les compresseurs centrifuges, axiaux et \u00e0 spirale. La compression volum\u00e9trique est une caract\u00e9ristique commune \u00e0 la plupart des compresseurs d'air. Les compresseurs volum\u00e9triques offrent les m\u00eames avantages et sont plus \u00e9conomes en \u00e9nergie pour les applications sans huile et \u00e0 gaz. Ce type de compression est g\u00e9n\u00e9ralement le plus adapt\u00e9 aux applications basse pression.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/air-compressor\/C_air-compressor-33.webp\" alt=\"compresseur d&#039;air\" width=\"800\" \/><\/p>\n<h2>sans huile<\/h2>\n<p>Si vous recherchez un compresseur d'air pour votre entreprise, pensez aux compresseurs sans huile. Ces mod\u00e8les offrent un fonctionnement plus propre et plus silencieux que les compresseurs traditionnels et n\u00e9cessitent moins d'entretien. Ils r\u00e9pondent \u00e9galement aux exigences de puret\u00e9 de l'air des normes ISO de classe 0 ou 1. Plus silencieux gr\u00e2ce \u00e0 un nombre r\u00e9duit de pi\u00e8ces mobiles, les compresseurs sans huile constituent une solution id\u00e9ale pour de nombreuses applications commerciales.<br \/>La puret\u00e9 de l'air est essentielle dans de nombreux secteurs. M\u00eame une infime goutte d'huile peut endommager les \u00e9quipements de production ou les produits. Pour choisir le compresseur d'air sans huile le mieux adapt\u00e9 \u00e0 votre activit\u00e9, tenez compte du processus et du produit final. Avec l'am\u00e9lioration de la qualit\u00e9 de l'air, de plus en plus d'entreprises optent pour des compresseurs sans huile. Voici quelques avantages et inconv\u00e9nients de ces compresseurs\u00a0:<br \/>Lors du choix d'un compresseur d'air sans huile, il est important de comprendre la terminologie employ\u00e9e dans le secteur. La connaissance de ces termes vous permettra de choisir plus facilement le compresseur adapt\u00e9 \u00e0 vos besoins. L'ACTFM, ou d\u00e9bit d'air r\u00e9el en pieds cubes par minute, est une unit\u00e9 de mesure du volume d'air pomp\u00e9 en une minute dans des conditions nominales. Bien qu'il s'agisse d'un chiffre simple, il peut s'av\u00e9rer tr\u00e8s utile pour d\u00e9terminer le type de compresseur d'air le mieux adapt\u00e9 \u00e0 votre application.<br \/>La norme internationale ISO 8573-1 d\u00e9finit la qualit\u00e9 de l'air et propose des classifications de puret\u00e9. La classification la plus stricte est la classe 0. De nombreux fabricants affirment que leurs compresseurs d'air sans huile r\u00e9pondent \u00e0 cette norme. Cependant, un compresseur d'air sans huile de classe 0 ne garantit pas n\u00e9cessairement l'absence totale de contaminants dans l'air. En r\u00e9alit\u00e9, la classe 0 constitue la r\u00e9f\u00e9rence en mati\u00e8re de puret\u00e9 de l'air. Bien que la classe 0 repr\u00e9sente le niveau le plus \u00e9lev\u00e9, cela ne signifie pas que l'air est totalement exempt d'huile.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/air-compressor\/C_air-compressor-5.webp\" alt=\"compresseur d&#039;air\" width=\"800\" \/><\/p>\n<h2>double action<\/h2>\n<p>Un compresseur d'air \u00e0 double effet est un appareil qui utilise l'air comprim\u00e9 pour produire de l'\u00e9lectricit\u00e9. Son principe de fonctionnement repose sur un piston et une bielle. La bielle relie le vilebrequin au piston par l'interm\u00e9diaire d'axes et de chapeaux. Le piston se d\u00e9place gr\u00e2ce au piston. Les bielles sont g\u00e9n\u00e9ralement en acier au carbone forg\u00e9. Pour leur entretien, les compresseurs \u00e0 double effet n\u00e9cessitent un contr\u00f4le r\u00e9gulier et un nettoyage appropri\u00e9.<br \/>Le d\u00e9bit d'air d'un compresseur correspond au volume d'air que le piston peut d\u00e9placer dans un laps de temps donn\u00e9. Il est g\u00e9n\u00e9ralement exprim\u00e9 en pieds cubes par minute (m\u00b3\/min). Le calcul exact d\u00e9pend du type de cylindre et de la configuration du compresseur. Les cylindres \u00e0 simple effet peuvent avoir un d\u00e9bit c\u00f4t\u00e9 culasse ou c\u00f4t\u00e9 vilebrequin\u00a0; ces deux types de d\u00e9bit peuvent \u00eatre calcul\u00e9s \u00e0 l'aide de l'\u00e9quation du d\u00e9bit. Un compresseur d'air \u00e0 double effet utilise cette m\u00eame \u00e9quation. Les \u00e9quations 4 et 6 permettent de calculer le d\u00e9bit.<br \/>Les compresseurs d'air \u00e0 double effet poss\u00e8dent plusieurs cylindres et sont fabriqu\u00e9s en fonte. Ils sont refroidis par eau et leur piston est reli\u00e9 m\u00e9caniquement \u00e0 la bielle. Un compresseur \u00e0 double effet comprime l'air deux fois par tour de moteur. Un cylindre monte tandis que l'autre descend. Le piston descend, permettant \u00e0 l'air de p\u00e9n\u00e9trer par la soupape #1. Pendant le fonctionnement du compresseur, la temp\u00e9rature de l'air et du gaz augmente.<br \/>Les compresseurs d'air \u00e0 double effet offrent g\u00e9n\u00e9ralement une pression \u00e9lev\u00e9e et sont r\u00e9put\u00e9s pour leur robustesse. Ils sont \u00e9galement dot\u00e9s d'un syst\u00e8me de refroidissement interm\u00e9diaire et d'une double compression. De ce fait, ces machines ont tendance \u00e0 durer plus longtemps que les compresseurs \u00e0 simple effet. Leur faible vitesse de rotation et leur double compression en font un outil indispensable dans l'industrie des compresseurs. Les compresseurs d'air \u00e0 double effet sont des appareils robustes et polyvalents.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/air-compressor\/C_air-compressor-6.webp\" alt=\"compresseur d&#039;air\" width=\"800\" \/><\/p>\n<h2>pressostat du r\u00e9servoir de carburant<\/h2>\n<p>Vous pouvez r\u00e9gler la pression dans le r\u00e9servoir du compresseur d'air en ajustant la pression diff\u00e9rentielle. Tournez le ressort principal dans le sens horaire ou antihoraire pour augmenter ou diminuer la pression. Cette soupape s'ouvre lorsque la pression est suffisamment basse pour d\u00e9marrer le compresseur. Si la pression est trop basse, la soupape doit rester ferm\u00e9e. Les pressions de d\u00e9marrage et d'arr\u00eat doivent \u00eatre r\u00e9gl\u00e9es correctement. Apr\u00e8s avoir r\u00e9gl\u00e9 la pression du r\u00e9servoir, v\u00e9rifiez l'hyst\u00e9r\u00e9sis du pressostat et r\u00e9glez la pression d'arr\u00eat souhait\u00e9e.<br \/>Si la pression dans le r\u00e9servoir chute en dessous du seuil de d\u00e9clenchement, le pressostat du r\u00e9servoir doit \u00eatre remplac\u00e9. Vous pouvez le tester avec un multim\u00e8tre. Assurez-vous qu'il n'est pas endommag\u00e9. Si vous ne le trouvez pas, examinez les autres composants. Remplacez toute pi\u00e8ce endommag\u00e9e ou manquante. Sinon, il est peut-\u00eatre temps de v\u00e9rifier le pressostat du r\u00e9servoir. Il vous faudra peut-\u00eatre d\u00e9monter le compresseur pour le retirer.<br \/>Le pressostat du r\u00e9servoir de carburant est un \u00e9l\u00e9ment essentiel du compresseur d'air. Il vous indique la quantit\u00e9 d'air fournie par le compresseur. Si votre r\u00e9servoir est endommag\u00e9, vos mesures seront erron\u00e9es. Si le pressostat est d\u00e9fectueux, il ne fonctionnera pas correctement et les mesures seront \u00e9galement incorrectes. Heureusement, il existe des solutions simples pour y rem\u00e9dier. Pour \u00e9viter ce probl\u00e8me, veillez \u00e0 maintenir le pressostat du r\u00e9servoir en bon \u00e9tat.<br \/>Lorsque la pression d'air dans le r\u00e9servoir atteint le seuil de d\u00e9clenchement, l'interrupteur laisse passer le courant. Le moteur et la pompe du compresseur d\u00e9marrent alors. Si la pression dans le r\u00e9servoir d\u00e9passe le seuil de coupure, l'interrupteur se d\u00e9clenche et arr\u00eate le compresseur, \u00e9vitant ainsi toute surpression. L'alimentation \u00e9lectrique du moteur reste cependant assur\u00e9e. Selon le mod\u00e8le de votre compresseur, vous pouvez ajuster les seuils de d\u00e9clenchement et de coupure.<\/p>\n<h2>source d'\u00e9nergie<\/h2>\n<p>L'alimentation \u00e9lectrique du compresseur d'air est primordiale. La plupart des compresseurs fonctionnent en 12 V CC, ce qui est id\u00e9al pour une utilisation automobile. Vous pouvez \u00e9galement opter pour une alimentation \u00e0 d\u00e9coupage, disponible pour environ $20. Quel que soit votre choix, assurez-vous qu'elle puisse supporter le courant maximal du compresseur. Vous trouverez des alimentations de toutes puissances, de 0,25 CV \u00e0 5 CV.<br \/>La tension requise pour un compresseur d'air triphas\u00e9 varie. Ces compresseurs n\u00e9cessitent trois c\u00e2bles d'alimentation distincts et un tableau \u00e9lectrique triphas\u00e9. En effet, un tableau \u00e9lectrique standard de 120\/240 volts est insuffisant pour alimenter un compresseur triphas\u00e9. De plus, les compresseurs triphas\u00e9s requi\u00e8rent trois fils isol\u00e9s distincts pour les circuits du moteur thermique et du moteur \u00e9lectrique. Ils ne n\u00e9cessitent pas de fil neutre.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/air-compressor\/air-compressor-L1.webp\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/air-compressor\/air-compressor-L2.webp\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Item Description Item Description Product Featuresone.Taper relationship,no bearing and free upkeep of motor.2.IP65 protection PM motor.3.Intergrated PTC proctection for PM motor.4.High quality PM motor.five.Higher dependable PM motor supplier.6.Higher performance airend.seven.Newest V\/F inverter.eight.Easy upkeep.9.All in 1 layout. Solution Types Benefits Software About SCR In addition,we have exported our goods to a lot more than\u00a055\u00a0countries including in [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[4,5,7,8,188,190,191,192,15,16,17,18,20,194,195,22,196,197,198,199,200,311,114,209],"class_list":["post-106","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-air-air-compressor","tag-air-compressor","tag-air-compressor-air-compressor","tag-air-compressor-china","tag-air-compressor-dryer","tag-air-compressor-with-dryer","tag-air-compressor-with-tank","tag-air-tank-compressor","tag-china-air-compressor","tag-china-compressor","tag-china-compressor-air","tag-compressor","tag-compressor-air-compressor","tag-compressor-air-dryer","tag-compressor-air-tank","tag-compressor-compressor","tag-compressor-dryer","tag-compressor-tank","tag-compressor-tank-air","tag-compressor-with-air-dryer","tag-dryer-compressor","tag-laser-cutting-air-compressor","tag-quality-air-compressor","tag-tank-compressor"],"_links":{"self":[{"href":"https:\/\/aircompressorforlasercutter.com\/fr\/wp-json\/wp\/v2\/posts\/106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aircompressorforlasercutter.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aircompressorforlasercutter.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aircompressorforlasercutter.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aircompressorforlasercutter.com\/fr\/wp-json\/wp\/v2\/comments?post=106"}],"version-history":[{"count":0,"href":"https:\/\/aircompressorforlasercutter.com\/fr\/wp-json\/wp\/v2\/posts\/106\/revisions"}],"wp:attachment":[{"href":"https:\/\/aircompressorforlasercutter.com\/fr\/wp-json\/wp\/v2\/media?parent=106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aircompressorforlasercutter.com\/fr\/wp-json\/wp\/v2\/categories?post=106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aircompressorforlasercutter.com\/fr\/wp-json\/wp\/v2\/tags?post=106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}