{"id":123,"date":"2022-11-11T18:47:09","date_gmt":"2022-11-11T18:47:09","guid":{"rendered":"https:\/\/aircompressorforlasercutter.com\/china-owen-new-technology-jn-30v-2-cylinder-3hp-50ltr-50-litre-air-compressor-3hp-cheap-mini-air-compressor-wholesaler\/"},"modified":"2022-11-11T18:47:09","modified_gmt":"2022-11-11T18:47:09","slug":"china-owen-new-technology-jn-30v-2-cylinder-3hp-50ltr-50-litre-air-compressor-3hp-cheap-mini-air-compressor-wholesaler","status":"publish","type":"post","link":"https:\/\/aircompressorforlasercutter.com\/pt\/application\/compressor-de-ar-mini-de-30-litros-2-cilindros-3-hp-tecnologia-owen-chinesa-jn-30v-50-litros-3-hp-atacado\/","title":{"rendered":"Compressor de ar China Owen New Technology Jn-30V de 2 cilindros, 3 HP e 50 litros (50 litros) - Mini compressor de ar barato para atacado."},"content":{"rendered":"<p>Ind\u00fastrias aplic\u00e1veis: Lojas de materiais de constru\u00e7\u00e3o, gr\u00e1ficas, oficinas de reparo de m\u00e1quinas, energia e minera\u00e7\u00e3o, obras de constru\u00e7\u00e3o civil, outras.<br \/>Espa\u00e7o para exposi\u00e7\u00e3o: Nenhum<br \/>Problema: Novo<br \/>Tipo: PIST\u00c3O<br \/>Configura\u00e7\u00e3o: Port\u00e1til<br \/>Recurso energ\u00e9tico: Energia CA<br \/>Tipo de lubrifica\u00e7\u00e3o: Lubrificado<br \/>Silenciar: N\u00c3O<br \/>N\u00famero do modelo: JN-30V<br \/>Voltagem: 220V\/50Hz<br \/>Dimens\u00f5es (C*L*A): 70*31*69<br \/>Garantia: 1 ano<br \/>Executando trabalho Tens\u00e3o: 8 bar<br \/>Capacidade de ar: 250 L\/min<br \/>Equipamentos: Veja o relat\u00f3rio: Oferecido<br \/>V\u00eddeo da inspe\u00e7\u00e3o de sa\u00edda: Fornecido<br \/>Tipo de marketing: Solu\u00e7\u00e3o regular<br \/>Garantia dos componentes principais: 1 ano<br \/>Componentes principais: Bomba, Motor<br \/>Tipo de gasolina: Ar<br \/>Identifica\u00e7\u00e3o do item: Compressor de ar de a\u00e7\u00e3o imediata<br \/>Aplica\u00e7\u00e3o: Ferramentas industriais comuns<br \/>Pot\u00eancia: 2,2 kW\/3 bar<br \/>Press\u00e3o: 8 bar\/115 psi<br \/>Potencial: 250 L\/min<br \/>Tanque: 50L<br \/>Uso: Compress\u00e3o de ar<br \/>OEM\/ODM: Ajuda<br \/>Quantidade m\u00ednima para encomenda: 20 unidades<br \/>Especifica\u00e7\u00f5es da embalagem: Caixa de papel\u00e3o, linha WLLDEN, caixa alveolar, caixa de piquete fechada<br \/>Porto: Hangzhou<\/p>\n<p>Exposi\u00e7\u00e3o de Mercadorias <table><tr><td colspan=\"1\" rowspan=\"1\">Nome do produto<\/td><td colspan=\"1\" rowspan=\"1\">Compressor de ar de acionamento direto<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Poder<\/td><td colspan=\"1\" rowspan=\"1\">2,2 kW\/3 bar<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Press\u00e3o<\/td><td colspan=\"1\" rowspan=\"1\">8bar<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Capacidade<\/td><td colspan=\"1\" rowspan=\"1\">250 L\/min<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Tanque<\/td><td colspan=\"1\" rowspan=\"1\">50L<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">OEM\/ODM<\/td><td colspan=\"1\" rowspan=\"1\">Apoiar<\/td><\/tr><\/table> Novidades Por que nos escolher Envio e entrega e pagamento Perguntas frequentes <font>Um. Quem somos n\u00f3s?<\/font>Somos uma empresa sediada em Zhangzhou, China, desde 2011, com atua\u00e7\u00e3o no Sudeste Asi\u00e1tico (00.00%), Am\u00e9rica do Sul (00.00%), Europa Oriental (00.00%), \u00c1frica (00.00%), Oriente M\u00e9dio (00.00%) e Europa Ocidental (00.00%). Nossa equipe comercial conta com aproximadamente 51 a 100 pessoas.<font>2. Como podemos prometer alta qualidade?<\/font>Amostras de pr\u00e9-produ\u00e7\u00e3o s\u00e3o sempre produzidas antes da produ\u00e7\u00e3o em massa. A \u00faltima inspe\u00e7\u00e3o \u00e9 realizada sempre antes do envio.<font>Tr\u00eas. O que voc\u00ea pode obter de n\u00f3s?<\/font>Compressor de ar, bomba de ar<font>Quatro. Por que voc\u00ea deveria comprar de n\u00f3s e n\u00e3o de outros fornecedores?<\/font>A HangZhou OWEN ELECTRO-Machinery CO., LTD \u00e9 uma fabricante especializada em compressores de ar. Somos uma empresa moderna que combina pesquisa cient\u00edfica, desenvolvimento e produ\u00e7\u00e3o.<font><font>Cinco. Que fornecedores podemos disponibilizar?<\/font><\/font>Termos de entrega aprovados: FOB, CFR, CIF, EXW. Moeda de pagamento aceita: USD. Formas de pagamento aceitas: T\/T, L\/C. Idiomas falados: ingl\u00eas, chin\u00eas.<\/p>\n<p>\n<h2>O que observar em um compressor de ar<\/h2>\n<p>Se voc\u00ea precisa comprar um compressor de ar, \u00e9 importante saber o que procurar. Os compressores de ar dispon\u00edveis no mercado s\u00e3o classificados de acordo com sua vaz\u00e3o (CFM), dispositivos de seguran\u00e7a e bombas. Existem diversas diferen\u00e7as entre compressores de ar lubrificados e isentos de \u00f3leo que voc\u00ea deve conhecer antes de comprar. Para entender melhor a diferen\u00e7a entre esses tipos de compressores de ar, continue lendo. Este artigo ir\u00e1 gui\u00e1-lo por essas diferen\u00e7as.<\/p>\n<h2>Bombear<\/h2>\n<p>Se voc\u00ea procura um compressor de ar de qualidade, veio ao lugar certo. Uma boa bomba de compressor de ar fornecer\u00e1 alta press\u00e3o para tudo, desde pneus a barcos e muito mais. Existem centenas de modelos diferentes para escolher, e a grande vantagem de comprar de um fabricante chin\u00eas \u00e9 a enorme variedade de op\u00e7\u00f5es dispon\u00edveis. Mais importante ainda, os fabricantes chineses podem personalizar equipamentos pneum\u00e1ticos, como compressores de ar, a pre\u00e7os acess\u00edveis.<br \/>Uma bomba de ar de boa qualidade n\u00e3o quebra facilmente e voc\u00ea poder\u00e1 us\u00e1-la por muitos anos. Escolher uma bomba de alta qualidade ajudar\u00e1 voc\u00ea a evitar muitos problemas na estrada, como paradas n\u00e3o planejadas e custos de instala\u00e7\u00e3o. Al\u00e9m disso, uma bomba do mesmo fabricante do seu compressor de ar \u00e9 a melhor op\u00e7\u00e3o para garantir o desempenho ideal. Abaixo, listamos algumas dicas para encontrar uma bomba de qualidade para o seu compressor de ar.<br \/>O compressor de ar \u00e9 uma inven\u00e7\u00e3o importante, por\u00e9m comum. Sem ele, nossas vidas seriam completamente diferentes. Sem uma bomba, n\u00e3o ter\u00edamos \u00e1gua quente do aquecimento central, nem o calor da geladeira. N\u00e3o conseguir\u00edamos encher pneus de bicicleta nem abastecer carros. As bombas s\u00e3o vitais para todos os tipos de m\u00e1quinas. Ent\u00e3o, por que \u00e9 importante escolher o produto certo? A resposta pode te surpreender.<br \/>Diferentes tipos de bombas s\u00e3o usados \u200b\u200bpara diferentes aplica\u00e7\u00f5es. As bombas de deslocamento positivo movem um volume fixo de fluido e o direcionam para um dreno. Esse projeto garante um fluxo constante a uma velocidade constante, independentemente da press\u00e3o de descarga. As bombas centr\u00edfugas funcionam de maneira diferente. O rotor acelera o fluido, convertendo a energia de entrada em energia cin\u00e9tica. Esse tipo de bomba \u00e9 mais comumente usado em minas, sistemas de ar condicionado, plantas industriais e controle de enchentes.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/air-compressor\/C_air-compressor-11.webp\" alt=\"compressor de ar\" width=\"800\" \/><\/p>\n<h2>equipamentos de seguran\u00e7a<\/h2>\n<p>Existem v\u00e1rios itens de seguran\u00e7a que voc\u00ea deve verificar ao usar um compressor de ar. Primeiro, verifique a conex\u00e3o do filtro de ar \u00e0 entrada de ar. Se estiverem soltos, as pe\u00e7as podem se separar e causar ferimentos. Outro item de seguran\u00e7a importante \u00e9 a v\u00e1lvula de fechamento. Ao trabalhar perto de ar comprimido, a v\u00e1lvula de fechamento deve estar ao alcance e \u00e0 vista. As partes m\u00f3veis e outros equipamentos devem ser protegidos com capas de prote\u00e7\u00e3o. Verifique a v\u00e1lvula de seguran\u00e7a e substitua as pe\u00e7as danificadas.<br \/>Os discos de ruptura s\u00e3o discos de cobre localizados no resfriador de ar. Quando a press\u00e3o do ar excede um determinado limite, eles se rompem. Os fus\u00edveis cont\u00eam materiais que derretem a altas temperaturas. O compressor deve possuir um alarme de press\u00e3o do \u00f3leo lubrificante e um sinal de desligamento autom\u00e1tico. Se esses dois dispositivos de seguran\u00e7a falharem, o compressor deve ser desligado imediatamente. O disco de ruptura deve ser inspecionado pelo menos semanalmente para garantir que n\u00e3o se rompa sob press\u00e3o.<br \/>Se o n\u00edvel de press\u00e3o estiver muito alto, o dispositivo de prote\u00e7\u00e3o contra sobrecorrente corta a energia do motor. Ele tamb\u00e9m desliga automaticamente o compressor quando a mangueira se rompe ou o volume de ar excede um n\u00edvel predefinido. O dispositivo deve ser instalado no compressor de ar para evitar acidentes. Sua fun\u00e7\u00e3o \u00e9 proteger o operador contra danos. Se os funcion\u00e1rios n\u00e3o seguirem essas medidas de seguran\u00e7a, podem causar danos ao equipamento.<br \/>Para garantir a seguran\u00e7a ao operar o compressor de ar, use \u00f3culos de prote\u00e7\u00e3o e luvas. O ar comprimido pode causar les\u00f5es oculares, e os \u00f3culos de prote\u00e7\u00e3o oferecem uma barreira protetora. Al\u00e9m disso, o cabo retr\u00e1til evita trope\u00e7os e refor\u00e7a o excesso de cabo. Mantenha as m\u00e3os e o corpo afastados do bico de ar para evitar que voc\u00ea seja atingido pelo ar comprimido.<\/p>\n<h2>Classifica\u00e7\u00e3o CFM<\/h2>\n<p>As classifica\u00e7\u00f5es PSI e CFM de um compressor de ar indicam a press\u00e3o e o volume que ele pode fornecer. PSI significa libras por polegada quadrada e mede a for\u00e7a e a press\u00e3o contidas em uma polegada quadrada de ar. Esses dois indicadores s\u00e3o igualmente importantes na escolha de um compressor de ar. Se voc\u00ea precisar de muito ar comprimido para uma aplica\u00e7\u00e3o espec\u00edfica, precisar\u00e1 de um compressor com PSI mais alto. Da mesma forma, se estiver usando ar comprimido em uma aplica\u00e7\u00e3o menor, um compressor com CFM baixo n\u00e3o fornecer\u00e1 pot\u00eancia suficiente para atender \u00e0s suas necessidades.<br \/>Ao comparar diferentes compressores de ar, preste muita aten\u00e7\u00e3o \u00e0 pot\u00eancia (HP) e \u00e0 vaz\u00e3o (CFM). Embora a pot\u00eancia do compressor seja essencial para algumas tarefas, n\u00e3o \u00e9 o aspecto mais importante. A vaz\u00e3o (CFM) de um compressor de ar determinar\u00e1 o tamanho do projeto que ele pode realizar e o tempo necess\u00e1rio para carreg\u00e1-lo. Certifique-se de entender as classifica\u00e7\u00f5es de vaz\u00e3o (CFM) e press\u00e3o (PSI) dos compressores que voc\u00ea pretende comprar, pois desconhecer essas informa\u00e7\u00f5es importantes pode causar frustra\u00e7\u00e3o e aumentar os custos.<br \/>Em geral, \u00e9 melhor escolher um compressor de ar com uma classifica\u00e7\u00e3o CFM superior ao tamanho da ferramenta pneum\u00e1tica. Isso garantir\u00e1 que o compressor tenha press\u00e3o suficiente para operar v\u00e1rias ferramentas simultaneamente com efici\u00eancia. Embora classifica\u00e7\u00f5es CFM menores possam ser suficientes para projetos menores, ferramentas maiores, como furadeiras, exigem muito ar. Portanto, quanto maior o CFM, maior e mais potente ser\u00e1 a ferramenta.<br \/>Depois de entender o CFM (p\u00e9s c\u00fabicos por minuto) de um compressor de ar, voc\u00ea pode come\u00e7ar a procurar a ferramenta certa. Voc\u00ea pode verificar a classifica\u00e7\u00e3o CFM do seu compressor de ar online, comentando abaixo. Se voc\u00ea n\u00e3o tiver certeza sobre o tamanho da sua ferramenta pneum\u00e1tica, sempre pode comprar um segundo compressor de ar. Esta \u00e9 uma \u00f3tima maneira de dobrar o CFM do seu compressor! Voc\u00ea ter\u00e1 mais ar para realizar mais trabalhos e seu compressor durar\u00e1 mais tempo.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/air-compressor\/C_air-compressor-1.webp\" alt=\"compressor de ar\" width=\"800\" \/><\/p>\n<h2>Falta de \u00f3leo e lubrifica\u00e7\u00e3o<\/h2>\n<p>Os compressores de ar isentos de \u00f3leo ocupam menos espa\u00e7o e exigem menos manuten\u00e7\u00e3o do que os compressores de ar lubrificados a \u00f3leo. Embora os compressores de ar lubrificados a \u00f3leo sejam mais caros e pesados \u200b\u200bdo que os compressores de ar isentos de \u00f3leo, eles tamb\u00e9m s\u00e3o ideais para uso estacion\u00e1rio. Os benef\u00edcios dos compressores de ar isentos de \u00f3leo incluem maior durabilidade e menores custos de manuten\u00e7\u00e3o. As vantagens e desvantagens de cada tipo s\u00e3o discutidas abaixo.<br \/>Os compressores de ar isentos de \u00f3leo s\u00e3o geralmente mais silenciosos do que os compressores de ar lubrificados a \u00f3leo. No entanto, voc\u00ea ainda pode perceber algum ru\u00eddo durante o uso. Para evitar isso, voc\u00ea deve escolher um compressor com entrada de ar silenciosa. Caso trabalhe pr\u00f3ximo a um compressor barulhento, considere adquirir um silenciador, um filtro de ar esportivo que reduza o ru\u00eddo do compressor.<br \/>Se voc\u00ea pretende usar o compressor de ar por um longo per\u00edodo, o modelo isento de \u00f3leo n\u00e3o \u00e9 a escolha ideal. Seu revestimento de Teflon se desgasta com o tempo, principalmente em temperaturas extremas. Al\u00e9m disso, os compressores de ar isentos de \u00f3leo possuem um grande n\u00famero de pe\u00e7as m\u00f3veis que exigem manuten\u00e7\u00e3o regular, enquanto os compressores de ar com \u00f3leo s\u00e3o \u00f3timos para quem n\u00e3o quer investir em pe\u00e7as extras.<br \/>Outra diferen\u00e7a importante entre compressores de ar isentos de \u00f3leo e lubrificados a \u00f3leo \u00e9 a lubrifica\u00e7\u00e3o. Os compressores de ar lubrificados a \u00f3leo requerem lubrifica\u00e7\u00e3o regular, enquanto os compressores de ar isentos de \u00f3leo j\u00e1 v\u00eam pr\u00e9-lubrificados. Eles possuem menos pe\u00e7as e s\u00e3o mais baratos. Os compressores de ar isentos de \u00f3leo s\u00e3o mais leves do que os compressores de ar lubrificados a \u00f3leo. Al\u00e9m de serem mais acess\u00edveis, os compressores de ar isentos de \u00f3leo s\u00e3o mais potentes e dur\u00e1veis.<br \/>Embora os compressores de ar a \u00f3leo sejam mais eficientes e dur\u00e1veis, eles geram muito calor. Al\u00e9m disso, s\u00e3o mais caros e exigem trocas regulares de \u00f3leo. Tamb\u00e9m s\u00e3o dif\u00edceis de transportar e precisam ser instalados permanentemente. Esses compressores de ar n\u00e3o s\u00e3o port\u00e1teis e requerem um local fixo. Portanto, considere suas necessidades antes de decidir qual tipo \u00e9 o melhor para voc\u00ea. Ao escolher um compressor de ar para sua empresa, certifique-se de pesquisar bastante.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/air-compressor\/C_air-compressor-2.webp\" alt=\"compressor de ar\" width=\"800\" \/><\/p>\n<h2>n\u00edvel de ru\u00eddo<\/h2>\n<p>Se voc\u00ea est\u00e1 se perguntando qual \u00e9 o n\u00edvel de ru\u00eddo de um compressor de ar, a resposta depende do seu equipamento espec\u00edfico e das condi\u00e7\u00f5es do ambiente de trabalho. Normalmente, os compressores de ar produzem de 40 a 90 decib\u00e9is de ru\u00eddo. Embora quanto menor o n\u00edvel de decib\u00e9is, mais silencioso ser\u00e1 o compressor. Compressores de ar maiores e mais potentes produzem n\u00edveis de ru\u00eddo mais altos do que os menores. Mas, independentemente do tamanho do compressor de ar, \u00e9 sempre recomend\u00e1vel usar protetores auriculares ao trabalhar perto dele.<br \/>Ao comprar um novo compressor de ar, o n\u00edvel de ru\u00eddo deve ser levado em considera\u00e7\u00e3o. Embora possa parecer um problema pequeno, existem muitas varia\u00e7\u00f5es desses equipamentos barulhentos. O tipo mais comum de compressor de ar \u00e9 a bomba de pist\u00e3o alternativo. Este modelo utiliza pist\u00f5es semelhantes aos de um motor para girar dentro de uma c\u00e2mara. O pist\u00e3o se move rapidamente e aprisiona ar proporcionalmente ao seu tamanho. Compressores de ar de pist\u00e3o \u00fanico geralmente s\u00e3o mais barulhentos do que os modelos de pist\u00e3o duplo, tamb\u00e9m conhecidos como compressores de dois cilindros.<br \/>Mesmo que voc\u00ea tenha o equipamento adequado para proteger sua audi\u00e7\u00e3o, ainda \u00e9 importante conhecer o n\u00edvel de ru\u00eddo de um compressor de ar. Mesmo que o ru\u00eddo n\u00e3o seja imediatamente perigoso, ele ainda pode causar perda auditiva tempor\u00e1ria ou permanente. Essa condi\u00e7\u00e3o \u00e9 chamada de perda auditiva induzida por ru\u00eddo, e um compressor de ar com um n\u00edvel sonoro de 80 ou superior pode causar danos auditivos permanentes. Voc\u00ea pode evitar poss\u00edveis danos \u00e0 sua audi\u00e7\u00e3o e prevenir acidentes simplesmente prestando aten\u00e7\u00e3o ao n\u00edvel de ru\u00eddo do seu compressor de ar.<br \/>Os compressores de ar s\u00e3o inerentemente ruidosos, mas se voc\u00ea tomar medidas para reduzir os n\u00edveis de ru\u00eddo, poder\u00e1 minimizar o inc\u00f4modo para vizinhos e colegas de trabalho. Por exemplo, instalar uma cabine ac\u00fastica na sua \u00e1rea de trabalho pode impedir que o compressor de ar fa\u00e7a tanto barulho quanto antes. Dependendo do seu espa\u00e7o de trabalho, voc\u00ea tamb\u00e9m pode tentar instalar uma mangueira de ar longa, o que reduzir\u00e1 os n\u00edveis de ru\u00eddo em at\u00e9 25%.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/air-compressor\/air-compressor-L1.webp\" alt=\"Compressor de ar China Owen New Technology Jn-30V de 2 cilindros, 3 HP e 50 litros (50 litros) - Mini compressor de ar barato para atacado. \"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/air-compressor\/air-compressor-L2.webp\" alt=\"Compressor de ar China Owen New Technology Jn-30V de 2 cilindros, 3 HP e 50 litros (50 litros) - Mini compressor de ar barato para atacado. \"><br \/>Editor por czh<\/p>","protected":false},"excerpt":{"rendered":"<p>Applicable Industries: Building Material Outlets, Printing Outlets, Machinery Mend Outlets, Energy &amp; Mining, Construction works\u00a0, OtherShowroom Spot: NoneIssue: NewKind: PISTONConfiguration: PortableEnergy Resource: AC EnergyLubrication Type: LubricatedMute: NODesign Number: JN-30VVoltage: 220V\/50HZDimension(L*W*H): 70*31*69Guarantee: 1 YrDoing work Strain: 8 barAir capacity: 250L\/MINEquipment Take a look at Report: OfferedVideo clip outgoing-inspection: SuppliedMarketing Type: Regular SolutionGuarantee of main elements: 1 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[633,634,445,635,4,5,446,636,7,8,218,160,220,326,15,16,17,225,18,637,20,22,233,163,235,164,165,638,166,167,639,640],"class_list":["post-123","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-2-cylinder","tag-2-cylinder-air-compressor","tag-3hp-air-compressor","tag-50-litre-air-compressor","tag-air-air-compressor","tag-air-compressor","tag-air-compressor-3hp","tag-air-compressor-50-litre","tag-air-compressor-air-compressor","tag-air-compressor-china","tag-air-compressor-cylinder","tag-air-compressor-mini","tag-air-cylinder","tag-cheap-air-compressor","tag-china-air-compressor","tag-china-compressor","tag-china-compressor-air","tag-china-cylinder","tag-compressor","tag-compressor-50-litre","tag-compressor-air-compressor","tag-compressor-compressor","tag-compressor-cylinder","tag-compressor-mini","tag-cylinder-air-compressor","tag-mini-air-compressor","tag-mini-air-compressor-china","tag-mini-air-cylinder","tag-mini-compressor","tag-mini-compressor-air","tag-mini-cylinder","tag-owen-air-compressor"],"_links":{"self":[{"href":"https:\/\/aircompressorforlasercutter.com\/pt\/wp-json\/wp\/v2\/posts\/123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aircompressorforlasercutter.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aircompressorforlasercutter.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aircompressorforlasercutter.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aircompressorforlasercutter.com\/pt\/wp-json\/wp\/v2\/comments?post=123"}],"version-history":[{"count":0,"href":"https:\/\/aircompressorforlasercutter.com\/pt\/wp-json\/wp\/v2\/posts\/123\/revisions"}],"wp:attachment":[{"href":"https:\/\/aircompressorforlasercutter.com\/pt\/wp-json\/wp\/v2\/media?parent=123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aircompressorforlasercutter.com\/pt\/wp-json\/wp\/v2\/categories?post=123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aircompressorforlasercutter.com\/pt\/wp-json\/wp\/v2\/tags?post=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}